{"id":4915,"date":"2024-02-14T07:09:43","date_gmt":"2024-02-14T12:09:43","guid":{"rendered":"https:\/\/espacesansviolence.org\/jeunesse\/?p=4915"},"modified":"2024-02-14T07:21:32","modified_gmt":"2024-02-14T12:21:32","slug":"le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans","status":"publish","type":"post","link":"https:\/\/espacesansviolence.org\/jeunesse\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\/","title":{"rendered":"Le Regroupement des organismes ESPACE du Qu\u00e9bec f\u00eate ses 35 ans !"},"content":{"rendered":"<p><strong>Qu\u00e9bec, le 14 f\u00e9vrier 2024<\/strong> \u2013 C\u2019est avec enthousiasme et fiert\u00e9 que le Regroupement des organismes ESPACE du Qu\u00e9bec (ROEQ) c\u00e9l\u00e8bre cette ann\u00e9e ses <a href=\"https:\/\/espacesansviolence.org\/jeunesse\/35ans\/\">35 ans<\/a> d\u2019expertise en pr\u00e9vention de la violence faite aux enfants.<\/p>\n<p>L\u2019expertise du ROEQ et des organismes ESPACE en mati\u00e8re de pr\u00e9vention de la violence faite aux enfants est unique. L\u2019approche d\u2019ESPACE est l\u2019une des rares \u00e0 aborder directement la violence faite aux enfants sous toutes ses formes, en visant \u00e0 la fois les adultes et les enfants de 3 \u00e0 12 ans, via des ateliers de pr\u00e9vention offerts dans les milieux scolaires et les services de garde du Qu\u00e9bec. Le ROEQ et ses membres travaillent \u00e9galement au d\u00e9veloppement d\u2019une grande <a href=\"https:\/\/espacesansviolence.org\/jeunesse\/espace-sans-violence-zone-prevention\/#outils\">vari\u00e9t\u00e9 d\u2019outils de pr\u00e9vention<\/a> pour la communaut\u00e9. Divers guides, feuillets th\u00e9matiques, capsules vid\u00e9o, ainsi qu\u2019un jeu en ligne en pr\u00e9vention de la violence, <a href=\"https:\/\/espacesansviolence.org\/jeunesse\/espace-sans-violence-nos-actions\/#realisations\"><em>FUTURAVILLE\u00a0: ensemble contre la violence\u00a0!<\/em>,<\/a> ont notamment \u00e9t\u00e9 cr\u00e9\u00e9s, permettant d\u2019\u00e9largir le travail de pr\u00e9vention de la violence aupr\u00e8s de tous les enfants et des adultes \u00e0 travers la province.<\/p>\n<p>Le ROEQ travaille constamment au d\u00e9veloppement de son expertise; son programme de pr\u00e9vention ayant, entre autres, \u00e9t\u00e9 adapt\u00e9 pour les enfants issus de la neurodiversit\u00e9. Du contenu sp\u00e9cifique pour aborder la violence sur Internet et les notions de cybers\u00e9curit\u00e9 a \u00e9galement \u00e9t\u00e9 cr\u00e9\u00e9. De plus, le ROEQ est activement mobilis\u00e9 au sein du mouvement de l\u2019action communautaire autonome (ACA), ainsi que dans la communaut\u00e9 pour la reconnaissance et le respect des droits des enfants.<\/p>\n<p>Au fil des ans, ce sont <strong>490\u00a0532 enfants<\/strong> et <strong>117 626 adultes <\/strong>qui ont \u00e9t\u00e9 sensibilis\u00e9s gr\u00e2ce aux ateliers de pr\u00e9vention ESPACE. Dans le cadre de ses 35 ans, le ROEQ invite la population \u00e0 d\u00e9couvrir la mission d\u2019ESPACE et le travail colossal de pr\u00e9vention r\u00e9alis\u00e9 par les organismes ESPACE dans la communaut\u00e9\u00a0!<\/p>\n<p>Visitez le site Web ESPACE et suivez-nous sur les m\u00e9dias sociaux ! Une foule d\u2019informations et d\u2019outils seront partag\u00e9s dans les prochaines semaines\u00a0!<\/p>\n<p><strong>35 ans d\u2019action pour la reconnaissance et le respect des droits des enfants, \u00e7a se f\u00eate\u00a0!<\/strong><\/p>\n<p><strong>\u00a0<\/strong>Depuis 35 ans, le ROEQ est engag\u00e9 \u00e0 mobiliser la communaut\u00e9 afin que la pr\u00e9vention de toutes les formes de violences faites aux enfants soit une priorit\u00e9 collective. Dans une perspective de changement social, le ROEQ sensibilise la population afin de reconnaitre et respecter les droits des enfants. Il mobilise et accompagne \u00e9galement les organismes ESPACE dans le d\u00e9veloppement d\u2019actions et d\u2019expertises. Neuf <a href=\"https:\/\/espacesansviolence.org\/jeunesse\/espace-sans-violence-nous-joindre\/#organismes\">organismes ESPACE<\/a><strong> sont pr\u00e9sents sur le territoire qu\u00e9b\u00e9cois et sont membres du <\/strong><a href=\"https:\/\/espacesansviolence.org\/jeunesse\/espace-sans-violence-nous-joindre\/#roeq\">ROEQ<\/a><strong>.<\/strong><\/p>\n<p><strong>\u00a0<\/strong>-30 &#8211;<\/p>\n<p><strong>Contact\u00a0:<\/strong><\/p>\n<p>Karine Savoie, Coordonnatrice aux communications et \u00e0 la visibilit\u00e9<\/p>\n<p>418-667-7070 poste 104<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qu\u00e9bec, le 14 f\u00e9vrier 2024 \u2013 C\u2019est avec enthousiasme et fiert\u00e9 que le Regroupement des organismes ESPACE du Qu\u00e9bec (ROEQ) c\u00e9l\u00e8bre cette ann\u00e9e ses 35 ans d\u2019expertise en pr\u00e9vention de&#8230;<\/p>\n","protected":false},"author":6,"featured_media":4922,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":{"0":"post-4915","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-communiques"},"cp_meta_data":{"_thumbnail_id":["4922"],"cmplz_hide_cookiebanner":[""],"_nectar_gallery_slider":["off"],"_nectar_quote_author":[""],"_nectar_quote":[""],"_nectar_link":[""],"_nectar_video_m4v":[""],"_nectar_video_ogv":[""],"_nectar_video_poster":[""],"_nectar_video_embed":[""],"_nectar_audio_mp3":[""],"_nectar_audio_ogg":[""],"_nectar_header_bg":[""],"_nectar_header_parallax":["off"],"_nectar_header_bg_height":[""],"_nectar_page_header_bg_alignment":["top"],"_nectar_header_bg_color":[""],"_nectar_header_font_color":[""],"_wpb_vc_js_status":["false"],"_yoast_wpseo_primary_category":["3"],"_yoast_wpseo_content_score":["30"],"_yoast_wpseo_estimated-reading-time-minutes":["3"],"_yoast_wpseo_wordproof_timestamp":[""],"nectar_blog_post_view_count":["791"],"_nectar_love":["0"],"_cmplz_scanned_post":["1"],"_cmplz_remote_scanned_post":["1"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le Regroupement des organismes ESPACE du Qu\u00e9bec f\u00eate ses 35 ans ! - ESPACE | Zone jeunesse<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/espacesansviolence.org\/jeunesse\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Regroupement des organismes ESPACE du Qu\u00e9bec f\u00eate ses 35 ans ! - ESPACE | Zone jeunesse\" \/>\n<meta property=\"og:description\" content=\"Qu\u00e9bec, le 14 f\u00e9vrier 2024 \u2013 C\u2019est avec enthousiasme et fiert\u00e9 que le Regroupement des organismes ESPACE du Qu\u00e9bec (ROEQ) c\u00e9l\u00e8bre cette ann\u00e9e ses 35 ans d\u2019expertise en pr\u00e9vention de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/espacesansviolence.org\/jeunesse\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\/\" \/>\n<meta property=\"og:site_name\" content=\"ESPACE | Zone jeunesse\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-14T12:09:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-14T12:21:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/espacesansviolence.org\/jeunesse\/wp-content\/uploads\/sites\/38\/2024\/02\/Banniere-ROEQ-35ans-web_Plan-de-travail-1-copie-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"3417\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Regroupement des organismes ESPACE du Qu\u00e9bec\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Regroupement des organismes ESPACE du Qu\u00e9bec\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/espacesansviolence.org\\\/jeunesse\\\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/espacesansviolence.org\\\/jeunesse\\\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\\\/\"},\"author\":{\"name\":\"Regroupement des organismes ESPACE du Qu\u00e9bec\",\"@id\":\"https:\\\/\\\/espacesansviolence.org\\\/jeunesse\\\/#\\\/schema\\\/person\\\/6767db77281477497e1f92772a230409\"},\"headline\":\"Le Regroupement des organismes ESPACE du Qu\u00e9bec f\u00eate ses 35 ans !\",\"datePublished\":\"2024-02-14T12:09:43+00:00\",\"dateModified\":\"2024-02-14T12:21:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/espacesansviolence.org\\\/jeunesse\\\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\\\/\"},\"wordCount\":472,\"image\":{\"@id\":\"https:\\\/\\\/espacesansviolence.org\\\/jeunesse\\\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/espacesansviolence.org\\\/jeunesse\\\/wp-content\\\/uploads\\\/sites\\\/38\\\/2024\\\/02\\\/Banniere-ROEQ-35ans-web_Plan-de-travail-1-copie-2.png\",\"articleSection\":[\"communiqu\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/espacesansviolence.org\\\/jeunesse\\\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\\\/\",\"url\":\"https:\\\/\\\/espacesansviolence.org\\\/jeunesse\\\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\\\/\",\"name\":\"Le Regroupement des organismes ESPACE du Qu\u00e9bec f\u00eate ses 35 ans ! - ESPACE | Zone jeunesse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/espacesansviolence.org\\\/jeunesse\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/espacesansviolence.org\\\/jeunesse\\\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/espacesansviolence.org\\\/jeunesse\\\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/espacesansviolence.org\\\/jeunesse\\\/wp-content\\\/uploads\\\/sites\\\/38\\\/2024\\\/02\\\/Banniere-ROEQ-35ans-web_Plan-de-travail-1-copie-2.png\",\"datePublished\":\"2024-02-14T12:09:43+00:00\",\"dateModified\":\"2024-02-14T12:21:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/espacesansviolence.org\\\/jeunesse\\\/#\\\/schema\\\/person\\\/6767db77281477497e1f92772a230409\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/espacesansviolence.org\\\/jeunesse\\\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/espacesansviolence.org\\\/jeunesse\\\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/espacesansviolence.org\\\/jeunesse\\\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\\\/#primaryimage\",\"url\":\"https:\\\/\\\/espacesansviolence.org\\\/jeunesse\\\/wp-content\\\/uploads\\\/sites\\\/38\\\/2024\\\/02\\\/Banniere-ROEQ-35ans-web_Plan-de-travail-1-copie-2.png\",\"contentUrl\":\"https:\\\/\\\/espacesansviolence.org\\\/jeunesse\\\/wp-content\\\/uploads\\\/sites\\\/38\\\/2024\\\/02\\\/Banniere-ROEQ-35ans-web_Plan-de-travail-1-copie-2.png\",\"width\":3417,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/espacesansviolence.org\\\/jeunesse\\\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/espacesansviolence.org\\\/jeunesse\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Regroupement des organismes ESPACE du Qu\u00e9bec f\u00eate ses 35 ans !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/espacesansviolence.org\\\/jeunesse\\\/#website\",\"url\":\"https:\\\/\\\/espacesansviolence.org\\\/jeunesse\\\/\",\"name\":\"ESPACE | Zone jeunesse\",\"description\":\"Pour une enfance sans violence!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/espacesansviolence.org\\\/jeunesse\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/espacesansviolence.org\\\/jeunesse\\\/#\\\/schema\\\/person\\\/6767db77281477497e1f92772a230409\",\"name\":\"Regroupement des organismes ESPACE du Qu\u00e9bec\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/espacesansviolence.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/avatar-wp-96x96.png\",\"url\":\"https:\\\/\\\/espacesansviolence.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/avatar-wp-96x96.png\",\"contentUrl\":\"https:\\\/\\\/espacesansviolence.org\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/avatar-wp-96x96.png\",\"caption\":\"Regroupement des organismes ESPACE du Qu\u00e9bec\"},\"url\":\"https:\\\/\\\/espacesansviolence.org\\\/jeunesse\\\/author\\\/roeq\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Regroupement des organismes ESPACE du Qu\u00e9bec f\u00eate ses 35 ans ! - ESPACE | Zone jeunesse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/espacesansviolence.org\/jeunesse\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Regroupement des organismes ESPACE du Qu\u00e9bec f\u00eate ses 35 ans ! - ESPACE | Zone jeunesse","og_description":"Qu\u00e9bec, le 14 f\u00e9vrier 2024 \u2013 C\u2019est avec enthousiasme et fiert\u00e9 que le Regroupement des organismes ESPACE du Qu\u00e9bec (ROEQ) c\u00e9l\u00e8bre cette ann\u00e9e ses 35 ans d\u2019expertise en pr\u00e9vention de...","og_url":"https:\/\/espacesansviolence.org\/jeunesse\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\/","og_site_name":"ESPACE | Zone jeunesse","article_published_time":"2024-02-14T12:09:43+00:00","article_modified_time":"2024-02-14T12:21:32+00:00","og_image":[{"width":3417,"height":1500,"url":"https:\/\/espacesansviolence.org\/jeunesse\/wp-content\/uploads\/sites\/38\/2024\/02\/Banniere-ROEQ-35ans-web_Plan-de-travail-1-copie-2.png","type":"image\/png"}],"author":"Regroupement des organismes ESPACE du Qu\u00e9bec","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Regroupement des organismes ESPACE du Qu\u00e9bec","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/espacesansviolence.org\/jeunesse\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\/#article","isPartOf":{"@id":"https:\/\/espacesansviolence.org\/jeunesse\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\/"},"author":{"name":"Regroupement des organismes ESPACE du Qu\u00e9bec","@id":"https:\/\/espacesansviolence.org\/jeunesse\/#\/schema\/person\/6767db77281477497e1f92772a230409"},"headline":"Le Regroupement des organismes ESPACE du Qu\u00e9bec f\u00eate ses 35 ans !","datePublished":"2024-02-14T12:09:43+00:00","dateModified":"2024-02-14T12:21:32+00:00","mainEntityOfPage":{"@id":"https:\/\/espacesansviolence.org\/jeunesse\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\/"},"wordCount":472,"image":{"@id":"https:\/\/espacesansviolence.org\/jeunesse\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\/#primaryimage"},"thumbnailUrl":"https:\/\/espacesansviolence.org\/jeunesse\/wp-content\/uploads\/sites\/38\/2024\/02\/Banniere-ROEQ-35ans-web_Plan-de-travail-1-copie-2.png","articleSection":["communiqu\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/espacesansviolence.org\/jeunesse\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\/","url":"https:\/\/espacesansviolence.org\/jeunesse\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\/","name":"Le Regroupement des organismes ESPACE du Qu\u00e9bec f\u00eate ses 35 ans ! - ESPACE | Zone jeunesse","isPartOf":{"@id":"https:\/\/espacesansviolence.org\/jeunesse\/#website"},"primaryImageOfPage":{"@id":"https:\/\/espacesansviolence.org\/jeunesse\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\/#primaryimage"},"image":{"@id":"https:\/\/espacesansviolence.org\/jeunesse\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\/#primaryimage"},"thumbnailUrl":"https:\/\/espacesansviolence.org\/jeunesse\/wp-content\/uploads\/sites\/38\/2024\/02\/Banniere-ROEQ-35ans-web_Plan-de-travail-1-copie-2.png","datePublished":"2024-02-14T12:09:43+00:00","dateModified":"2024-02-14T12:21:32+00:00","author":{"@id":"https:\/\/espacesansviolence.org\/jeunesse\/#\/schema\/person\/6767db77281477497e1f92772a230409"},"breadcrumb":{"@id":"https:\/\/espacesansviolence.org\/jeunesse\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/espacesansviolence.org\/jeunesse\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/espacesansviolence.org\/jeunesse\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\/#primaryimage","url":"https:\/\/espacesansviolence.org\/jeunesse\/wp-content\/uploads\/sites\/38\/2024\/02\/Banniere-ROEQ-35ans-web_Plan-de-travail-1-copie-2.png","contentUrl":"https:\/\/espacesansviolence.org\/jeunesse\/wp-content\/uploads\/sites\/38\/2024\/02\/Banniere-ROEQ-35ans-web_Plan-de-travail-1-copie-2.png","width":3417,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/espacesansviolence.org\/jeunesse\/le-regroupement-des-organismes-espace-du-quebec-fete-ses-35-ans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/espacesansviolence.org\/jeunesse\/"},{"@type":"ListItem","position":2,"name":"Le Regroupement des organismes ESPACE du Qu\u00e9bec f\u00eate ses 35 ans !"}]},{"@type":"WebSite","@id":"https:\/\/espacesansviolence.org\/jeunesse\/#website","url":"https:\/\/espacesansviolence.org\/jeunesse\/","name":"ESPACE | Zone jeunesse","description":"Pour une enfance sans violence!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/espacesansviolence.org\/jeunesse\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/espacesansviolence.org\/jeunesse\/#\/schema\/person\/6767db77281477497e1f92772a230409","name":"Regroupement des organismes ESPACE du Qu\u00e9bec","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/espacesansviolence.org\/wp-content\/uploads\/2022\/12\/avatar-wp-96x96.png","url":"https:\/\/espacesansviolence.org\/wp-content\/uploads\/2022\/12\/avatar-wp-96x96.png","contentUrl":"https:\/\/espacesansviolence.org\/wp-content\/uploads\/2022\/12\/avatar-wp-96x96.png","caption":"Regroupement des organismes ESPACE du Qu\u00e9bec"},"url":"https:\/\/espacesansviolence.org\/jeunesse\/author\/roeq\/"}]}},"_links":{"self":[{"href":"https:\/\/espacesansviolence.org\/jeunesse\/wp-json\/wp\/v2\/posts\/4915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacesansviolence.org\/jeunesse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacesansviolence.org\/jeunesse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacesansviolence.org\/jeunesse\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/espacesansviolence.org\/jeunesse\/wp-json\/wp\/v2\/comments?post=4915"}],"version-history":[{"count":0,"href":"https:\/\/espacesansviolence.org\/jeunesse\/wp-json\/wp\/v2\/posts\/4915\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacesansviolence.org\/jeunesse\/wp-json\/wp\/v2\/media\/4922"}],"wp:attachment":[{"href":"https:\/\/espacesansviolence.org\/jeunesse\/wp-json\/wp\/v2\/media?parent=4915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacesansviolence.org\/jeunesse\/wp-json\/wp\/v2\/categories?post=4915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacesansviolence.org\/jeunesse\/wp-json\/wp\/v2\/tags?post=4915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}